{"id":15229,"date":"2016-11-22T15:18:33","date_gmt":"2016-11-22T14:18:33","guid":{"rendered":"https:\/\/preprod.i4ce.org\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/"},"modified":"2022-07-15T21:51:15","modified_gmt":"2022-07-15T19:51:15","slug":"presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation","status":"publish","type":"publication","link":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/","title":{"rendered":"Presentation from Ecofys &#8211; Impacts of a global carbon price on consumption and value creation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":49094,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"type_publication":[80],"class_list":["post-15229","publication","type-publication","status-publish","has-post-thumbnail","hentry","type_publication-pieces-jointes-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/\" \/>\n<meta property=\"og:site_name\" content=\"I4CE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T19:51:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.i4ce.org\/wp-content\/uploads\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"842\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@I4CE_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/\",\"url\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/\",\"name\":\"Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.i4ce.org\\\/wp-content\\\/uploads\\\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg\",\"datePublished\":\"2016-11-22T14:18:33+00:00\",\"dateModified\":\"2022-07-15T19:51:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.i4ce.org\\\/wp-content\\\/uploads\\\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg\",\"contentUrl\":\"https:\\\/\\\/www.i4ce.org\\\/wp-content\\\/uploads\\\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg\",\"width\":842,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/publication\\\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.i4ce.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentation from Ecofys &#8211; Impacts of a global carbon price on consumption and value creation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#website\",\"url\":\"https:\\\/\\\/www.i4ce.org\\\/\",\"name\":\"I4CE\",\"description\":\"Institute for Climat Economics\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.i4ce.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#organization\",\"name\":\"I4CE\",\"url\":\"https:\\\/\\\/www.i4ce.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.i4ce.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_I4CE-HD-qdr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.i4ce.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_I4CE-HD-qdr.jpg\",\"width\":213,\"height\":247,\"caption\":\"I4CE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.i4ce.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/I4CE_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/i4ce\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLZEgZVIiYP6TSDrid7A3mQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/","og_locale":"en_US","og_type":"article","og_title":"Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE","og_url":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/","og_site_name":"I4CE","article_modified_time":"2022-07-15T19:51:15+00:00","og_image":[{"width":842,"height":595,"url":"https:\/\/www.i4ce.org\/wp-content\/uploads\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@I4CE_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/","url":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/","name":"Presentation from Ecofys - Impacts of a global carbon price on consumption and value creation - I4CE","isPartOf":{"@id":"https:\/\/www.i4ce.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/#primaryimage"},"image":{"@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.i4ce.org\/wp-content\/uploads\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg","datePublished":"2016-11-22T14:18:33+00:00","dateModified":"2022-07-15T19:51:15+00:00","breadcrumb":{"@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/#primaryimage","url":"https:\/\/www.i4ce.org\/wp-content\/uploads\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg","contentUrl":"https:\/\/www.i4ce.org\/wp-content\/uploads\/16-11-Ecofys_Carbon-pricing-Unlocked_Side-Event-COP22-pdf-image.jpg","width":842,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/www.i4ce.org\/en\/publication\/presentation-from-ecofys-impacts-of-a-global-carbon-price-on-consumption-and-value-creation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.i4ce.org\/en\/"},{"@type":"ListItem","position":2,"name":"Presentation from Ecofys &#8211; Impacts of a global carbon price on consumption and value creation"}]},{"@type":"WebSite","@id":"https:\/\/www.i4ce.org\/#website","url":"https:\/\/www.i4ce.org\/","name":"I4CE","description":"Institute for Climat Economics","publisher":{"@id":"https:\/\/www.i4ce.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.i4ce.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.i4ce.org\/#organization","name":"I4CE","url":"https:\/\/www.i4ce.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.i4ce.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.i4ce.org\/wp-content\/uploads\/2022\/07\/logo_I4CE-HD-qdr.jpg","contentUrl":"https:\/\/www.i4ce.org\/wp-content\/uploads\/2022\/07\/logo_I4CE-HD-qdr.jpg","width":213,"height":247,"caption":"I4CE"},"image":{"@id":"https:\/\/www.i4ce.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/I4CE_","https:\/\/www.linkedin.com\/company\/i4ce\/","https:\/\/www.youtube.com\/channel\/UCLZEgZVIiYP6TSDrid7A3mQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/publication\/15229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/types\/publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/media\/49094"}],"wp:attachment":[{"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/media?parent=15229"}],"wp:term":[{"taxonomy":"type_publication","embeddable":true,"href":"https:\/\/www.i4ce.org\/en\/wp-json\/wp\/v2\/type_publication?post=15229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}